{"id":88811,"date":"2016-09-02T18:06:03","date_gmt":"2016-09-02T16:06:03","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=88811"},"modified":"2016-09-02T23:41:05","modified_gmt":"2016-09-02T21:41:05","slug":"ces-banques-qui-ne-font-plus-parler-delles-et-pourtant-par-francois-leclerc","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2016\/09\/02\/ces-banques-qui-ne-font-plus-parler-delles-et-pourtant-par-francois-leclerc\/","title":{"rendered":"<b>CES BANQUES QUI NE FONT PLUS PARLER D\u2019ELLES, ET POURTANT&#8230;<\/b> par Fran\u00e7ois Leclerc"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9.<\/p><\/blockquote>\n<p>Les grandes banques am\u00e9ricaines \u00e9tudient la possibilit\u00e9 d\u2019engager une action en justice contre la Fed, apprend-on dans les colonnes du Wall Street Journal. Rejoignant leurs cons\u0153urs europ\u00e9ennes, mais en empruntant d\u2019autres chemins, elles entendent elles aussi obtenir un assouplissement des contraintes qui p\u00e8sent sur elles sous la forme d\u2019un contr\u00f4le moins pesant.<\/p>\n<p><!--more--><\/p>\n<p>La Fed serait coupable de r\u00e9aliser dans l\u2019opacit\u00e9 ses tests de r\u00e9sistance annuels des \u00e9tablissements dont la taille du bilan d\u00e9passe 500 milliards de dollars (trente-trois l\u2019an dernier). Si elle a apport\u00e9 des pr\u00e9cisions aux mod\u00e8les math\u00e9matiques qu\u2019elle utilise, la banque centrale se refuse en effet \u00e0 d\u00e9voiler sa m\u00e9thodologie, craignant que les banquiers ne s\u2019en servent pour contourner ses analyses. Aux yeux de ceux-ci, elle interf\u00e8re dans leur conduite des affaires en interdisant la distribution des dividendes aux actionnaires et en influen\u00e7ant leur \u00e9valuation sur le march\u00e9.<\/p>\n<p>Dernier grief, la Fed d\u00e9cide unilat\u00e9ralement des sc\u00e9narios catastrophe dont elle teste l\u2019impact sur les bilans bancaires, susceptible de violer l\u2019Administrative Procedure Act. Il est loin le temps o\u00f9 les banques et les r\u00e9gulateurs r\u00e9glaient derri\u00e8res des portes capitonn\u00e9es leurs affaires, la crise financi\u00e8re est pass\u00e9e par l\u00e0, ne laissant pas la m\u00eame place \u00e0 la n\u00e9gociation. Au contraire, la Fed n\u2019h\u00e9site plus \u00e0 \u00e9pingler nomm\u00e9ment les banques qu\u2019elle estime fautives.<\/p>\n<p>Les m\u00e9gabanques supervis\u00e9es par la Fed vont-elles ou non passer \u00e0 l\u2019acte et engager une proc\u00e9dure ? Plut\u00f4t que de monter en premi\u00e8re ligne, elles pourraient pr\u00e9f\u00e9rer laisser agir des tiers, \u00e0 moins qu\u2019elles ne se satisfassent dans l\u2019imm\u00e9diat d\u2019un coup de semonce.<\/p>\n<p>Les banques europ\u00e9ennes peuvent de leur c\u00f4t\u00e9 se satisfaire d\u2019avoir tu\u00e9 la taxe sur les transactions financi\u00e8res, devenue un serpent de mer. Discr\u00e8tement, elles p\u00e8sent de tout leur poids aux c\u00f4t\u00e9s de leurs cons\u0153urs am\u00e9ricaines contre la poursuite de la politique de taux n\u00e9gatifs de la BCE et du Japon, ayant d\u00e9j\u00e0 obtenu que la Fed ne s\u2019y rallie pas. R\u00e9sultat, on aura not\u00e9 \u00e0 Jackson Hole, ou bien dans les r\u00e9centes d\u00e9clarations du FMI, que l\u2019accent est d\u00e9sormais mis sur les d\u00e9g\u00e2ts collat\u00e9raux que les mesures des banques centrales peuvent cr\u00e9er, en premier lieu les taux n\u00e9gatifs.<\/p>\n<p>En Europe, les syst\u00e8mes bancaires nationaux continuent d\u2019\u00eatre aux prises avec leur restructuration, la France continuant \u00e0 faire exception mais pour combien de temps\u00a0? Manifestement, le tour du syst\u00e8me bancaire allemand est venu, ses faiblesses ne pouvant plus \u00eatre dissimul\u00e9es. La saga du sauvetage du g\u00e9ant Deutsche Bank, qui est d\u00e9sormais valoris\u00e9 \u00e0 un tiers de sa valeur comptable, se poursuit. Apr\u00e8s avoir examin\u00e9 et rejet\u00e9 les options \u00e0 sa disposition, la banque allemande est \u00e0 la recherche d\u2019un nouveau mod\u00e8le, en raison de la faiblesse de son rendement que les taux bas ou n\u00e9gatifs accroissent encore.<\/p>\n<p>On a appris qu\u2019une fusion avec Commerzbank, la seconde grande banque allemande, a commenc\u00e9 \u00e0 \u00eatre \u00e9tudi\u00e9e par leurs dirigeants, ce qui aurait donn\u00e9 lieu \u00e0 la naissance d\u2019un colosse de 2.000 milliards d\u2019euros de taille de bilan. Dans le genre fuite en avant, on ne peut pas mieux trouver, et ce n\u2019est que partie remise. Une fois le m\u00e9nage et une cure d\u2019amaigrissement r\u00e9alis\u00e9s au sein de ces deux banques, la Commerzbank \u00e0 peine stabilis\u00e9e apr\u00e8s avoir \u00e9t\u00e9 renflou\u00e9e sur fonds publics d\u00e8s 2009, cet objectif resurgira sans nul doute. C\u2019est seulement ainsi que pourra \u00eatre dig\u00e9r\u00e9 l\u2019\u00e9norme paquet de produits d\u00e9riv\u00e9s que la Deutsche a en portefeuille, par la fusion des deux grandes banques malades.<\/p>\n<p>Exemple accompli de banque trop grosse pour faire faillite, la Deutsche n\u2019est pas seule en cause. Sous les instances pressantes de la BCE, la restructuration a d\u00e9but\u00e9 au niveau des Landesbanken, les banques des r\u00e9gions. Deux d\u2019entre elles, Bremer LB et Nord LB, vont fusionner afin d\u2019\u00e9viter une importante recapitalisation de la premi\u00e8re. Sur le march\u00e9 de la banque de d\u00e9tail, des caisses d\u2019\u00e9pargne et des coop\u00e9ratives, une consolidation s\u2019impose \u00e9galement en raison de l\u2019intense concurrence qui y r\u00e8gne.<\/p>\n<p>La Commission est silencieuse \u00e0 ce propos, ayant d\u2019autres soucis en t\u00eate. Pierre Moscovici, le commissaire aux affaires europ\u00e9ennes, a entam\u00e9 un num\u00e9ro d\u2019\u00e9quilibriste \u00e0 propos des r\u00e8gles du pacte de stabilit\u00e9. Un d\u00e9bat \u00e0 leur propos est \u00ab\u00a0l\u00e9gitime\u00a0\u00bb affirme-t-il, mais il ne doit pas remettre le pacte en cause, apportant comme pr\u00e9cision capitale que \u00ab je souhaite que le d\u00e9bat sur les r\u00e8gles soit un d\u00e9bat qui se d\u00e9roule dans les r\u00e8gles du pacte de stabilit\u00e9 et de croissance\u00a0\u00bb. De la haute voltige est au programme \u00e0 Bruxelles, Angela Merkel s\u2019\u00e9tant d\u00e9fauss\u00e9e sur la Commission.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. Les grandes banques am\u00e9ricaines \u00e9tudient la possibilit\u00e9 d\u2019engager une action en justice contre la Fed, apprend-on dans les colonnes du Wall Street Journal. Rejoignant leurs cons\u0153urs europ\u00e9ennes, mais en empruntant d\u2019autres chemins, elles entendent elles aussi obtenir un assouplissement des contraintes qui p\u00e8sent sur elles sous la forme d\u2019un contr\u00f4le moins pesant.<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[4980,538,195,417,4142],"class_list":["post-88811","post","type-post","status-publish","format-standard","hentry","category-monde-financier","tag-commerzbank","tag-deutsche-bank","tag-fed","tag-pacte-de-stabilite","tag-taux-negatifs"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/88811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=88811"}],"version-history":[{"count":8,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/88811\/revisions"}],"predecessor-version":[{"id":88822,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/88811\/revisions\/88822"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=88811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=88811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=88811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}